{"id":1750,"date":"2022-12-12T01:21:46","date_gmt":"2022-12-12T00:21:46","guid":{"rendered":"https:\/\/erumgroup.com\/economie-circulaire-collaborative-la-cle-du-progres\/"},"modified":"2026-02-18T16:13:46","modified_gmt":"2026-02-18T15:13:46","slug":"economie-circulaire-collaborative-la-cle-du-progres","status":"publish","type":"post","link":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/","title":{"rendered":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s"},"content":{"rendered":"\n<section class=\"divi-section\"><div class=\"divi-row\"><div class=\"divi-column\"><div class=\"divi-text\"><p><\/p>\r\n\r\n<p>Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9 Gr\u00e2ce \u00e0 notre exp\u00e9rience et \u00e0 notre apprentissage, nous avons trouv\u00e9 le moyen d\u2019obtenir les performances maximales de ce mat\u00e9riau, en tirant parti de toutes ses qualit\u00e9s et en r\u00e9duisant au minimum les d\u00e9chets g\u00e9n\u00e9r\u00e9s.<\/p>\r\n<p>L\u2019une des cl\u00e9s de la progression de la compagnie vers la circularit\u00e9 et la durabilit\u00e9 a \u00e9t\u00e9 notre constante \u00e9volution et adaptation aux besoins, tant sociaux qu\u2019environnementaux, en comptant toujours sur des partenaires strat\u00e9giques qui nous ont accompagn\u00e9s vers ce mod\u00e8le d\u2019\u00e9conomie circulaire.<\/p>\r\n<h3>Cl\u00e9s de l\u2019\u00e9conomie circulaire collaborative<\/h3>\r\n<ol>\r\n<li>\u00c9volution et innovation constantes.<\/li>\r\n<li>Collaboration avec des partenaires strat\u00e9giques.<\/li>\r\n<li>Mise en place de politiques de r\u00e9utilisation et de recirculation.<\/li>\r\n<li>R\u00e9duction des \u00e9missions de CO2.<\/li>\r\n<li>Utilisation de mat\u00e9riaux d\u2019origine post-consommation.<\/li>\r\n<li>Engagement en faveur des politiques Zero Waste<\/li>\r\n<li>\u00c9limination de l\u2019utilisation de substances restreintes ou dangereuses pour la sant\u00e9 humaine et l\u2019environnement.<\/li>\r\n<\/ol>\r\n<h3>Du mod\u00e8le lin\u00e9aire au mod\u00e8le circulaire<\/h3>\r\n<p>Avec la r\u00e9volution industrielle, un mod\u00e8le \u00e9conomique a \u00e9t\u00e9 \u00e9tabli, bas\u00e9 sur l\u2019extraction des mati\u00e8res premi\u00e8res, la production, la consommation et l\u2019\u00e9limination des produits, c\u2019est-\u00e0-dire un mod\u00e8le \u00e9conomique lin\u00e9aire. Pendant de nombreuses ann\u00e9es, ce syst\u00e8me a fonctionn\u00e9 et a stimul\u00e9 l\u2019\u00e9conomie du pays, mais aujourd\u2019hui, il est devenu insoutenable, surtout si l\u2019on pense \u00e0 garantir la survie de notre plan\u00e8te.<\/p>\r\n<p>En raison des probl\u00e8mes majeurs qui ont surgi \u00e0 cause du mod\u00e8le pr\u00e9c\u00e9dent, les gens ont commenc\u00e9 \u00e0 prendre conscience et \u00e0 rechercher des formes diff\u00e9rentes de mod\u00e8les \u00e9conomiques, donnant ainsi naissance \u00e0 l\u2019\u00e9conomie circulaire.<\/p>\r\n<p>Selon le rapport The Circularity GAP Report 2022, qui mesure l\u2019\u00e9conomie circulaire \u00e0 l\u2019\u00e9chelle mondiale et fournit une vue d\u2019ensemble des syst\u00e8mes \u00e9conomiques analys\u00e9s, seulement 8,6 % de tout ce qui a \u00e9t\u00e9 utilis\u00e9 en 2020 a \u00e9t\u00e9 recycl\u00e9, ce qui repr\u00e9sente un \u00e9cart de circularit\u00e9 de plus de 90 %.<\/p>\r\n<p>Le rapport montre \u00e9galement qu\u2019en 2019, la soci\u00e9t\u00e9 a d\u00e9pass\u00e9 les limites de l\u2019extraction et de la transformation, consommant 100 000 tonnes de ressources et g\u00e9n\u00e9rant la perte de 90 % de la biodiversit\u00e9, selon le Global Resources Outlook 2019.<\/p>\r\n<p>En Espagne nous progressons vers un mod\u00e8le plus durable gr\u00e2ce \u00e0 des politiques telles que la strat\u00e9gie espagnole d\u2019\u00e9conomie circulaire \u00ab Espagne circulaire 2030 \u00bb et son plan d\u2019action 2021-2023, qui \u00e9tablit une feuille de route pour promouvoir un nouveau mod\u00e8le de production et de consommation durables.<\/p>\r\n<p>Chez Erum, ce mod\u00e8le et ce changement de mentalit\u00e9 se pratiquent depuis longtemps, gr\u00e2ce \u00e0 notre volont\u00e9 d\u2019\u00eatre visionnaires et d\u2019interpr\u00e9ter l\u2019avenir, de consid\u00e9rer les g\u00e9n\u00e9rations futures, l\u2019h\u00e9ritage que nous voulons leur laisser tant sur le plan personnel qu\u2019environnemental, et les impacts que nous provoquons sur l\u2019environnement \u00e0 cause de notre activit\u00e9.<\/p>\r\n<p>En outre, tout cela ne serait pas possible sans une \u00e9quipe ad\u00e9quate de designers, d\u2019ing\u00e9nieurs, de techniciens de l\u2019environnement et des op\u00e9rations de r\u00e9cup\u00e9ration, entre autres, qui \u00e9tudient, d\u00e9veloppent, impl\u00e9mentent et ex\u00e9cutent tous ces processus bas\u00e9s sur la Circular Thinking.<\/p>\r\n<p>C\u2019est gr\u00e2ce \u00e0 ce type de d\u00e9veloppement \u00e9conomique qu\u2019est n\u00e9e l\u2019id\u00e9e de mettre en place un syst\u00e8me mondial de classification des cintres, le <a href=\"https:\/\/erumgroup.com\/rts\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Return To Source System (RTS)<\/a>.<\/p>\r\n<p>Erum collecte les cintres utilis\u00e9s par ses clients et les s\u00e9pare en deux cat\u00e9gories : les cintres \u00e0 r\u00e9utiliser (qui sont encore en conformit\u00e9 avec les crit\u00e8res de l\u2019entreprise) et les cintres \u00e0 recycler (qui ne peuvent plus accomplir leurs fonctions et sont broy\u00e9s pour obtenir de la mati\u00e8re premi\u00e8re).<\/p>\r\n<p><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-6916 size-full\" src=\"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/Nuevo-reto-empresarial.webp\" alt=\"d\u00e9fi commercial du groupe erum\" width=\"1200\" height=\"565\"><\/p>\r\n<h3>\u00c9conomie Circulaire Collaborative : Un nouveau d\u00e9fi pour les entrepises<\/h3>\r\n<p>Chez Erum, nous avons d\u00e9velopp\u00e9 un exemple clair d\u2019\u00e9conomie circulaire collaborative, gr\u00e2ce \u00e0 la mise en place du syst\u00e8me RTS et \u00e0 l\u2019\u00e9co-conception des cintres. L\u2019objectif est de faire en sorte que nos produits aient un cycle de vie plus long et que l\u2019entreprise dispose toujours de mati\u00e8res premi\u00e8res pour leur production.<\/p>\r\n<p>Ainsi, chez Erum, nous suivons une philosophie bas\u00e9e sur les 7R : Redesign \u2013 Recover \u2013 Reuse \u2013 Repair \u2013 Recycle \u2013 Reduce \u2013 Rethink, qui est n\u00e9cessaire pour la protection de notre plan\u00e8te.<\/p>\r\n<p>De votre c\u00f4t\u00e9, avez-vous d\u00e9j\u00e0 bascul\u00e9 vers le mod\u00e8le d\u2019\u00e9conomie circulaire collaborative ?<\/p>\r\n<p>Voulez-vous participer \u00e0 nos d\u00e9fis ?<\/p><div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9 Gr\u00e2ce \u00e0 notre exp\u00e9rience et \u00e0 notre apprentissage, nous avons trouv\u00e9 le moyen d\u2019obtenir les performances maximales de ce mat\u00e9riau, en tirant parti de toutes ses qualit\u00e9s et en r\u00e9duisant au minimum les d\u00e9chets g\u00e9n\u00e9r\u00e9s. L\u2019une des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-1750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-circular-thinking"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s - Erum<\/title>\n<meta name=\"description\" content=\"Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Chez Erum, ce mod\u00e8le et ce changement de mentalit\u00e9 se pratiquent depuis longtemps, gr\u00e2ce \u00e0 notre volont\u00e9 d\u2019\u00eatre visionnaires et d\u2019interpr\u00e9ter l\u2019avenir, de consid\u00e9rer les g\u00e9n\u00e9rations futures\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/\" \/>\n<meta property=\"og:site_name\" content=\"Erum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/plasticoserum\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-12T00:21:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T15:13:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/erumgroup.com\/wp-content\/uploads\/2022\/12\/noticias4-1024x563.webp\" \/>\n<meta name=\"author\" content=\"tttsergio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s\" \/>\n<meta name=\"twitter:description\" content=\"Chez Erum, ce mod\u00e8le et ce changement de mentalit\u00e9 se pratiquent depuis longtemps, gr\u00e2ce \u00e0 notre volont\u00e9 d\u2019\u00eatre visionnaires et d\u2019interpr\u00e9ter l\u2019avenir, de consid\u00e9rer les g\u00e9n\u00e9rations futures\" \/>\n<meta name=\"twitter:creator\" content=\"@Erumgroup\" \/>\n<meta name=\"twitter:site\" content=\"@Erumgroup\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tttsergio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/\"},\"author\":{\"name\":\"tttsergio\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#\\\/schema\\\/person\\\/80652ce28a8d027d641a57d62f8d823c\"},\"headline\":\"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s\",\"datePublished\":\"2022-12-12T00:21:46+00:00\",\"dateModified\":\"2026-02-18T15:13:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/\"},\"wordCount\":774,\"publisher\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/noticias4.webp\",\"articleSection\":[\"Circular Thinking\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/\",\"url\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/\",\"name\":\"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s - Erum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/noticias4.webp\",\"datePublished\":\"2022-12-12T00:21:46+00:00\",\"dateModified\":\"2026-02-18T15:13:46+00:00\",\"description\":\"Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/economie-circulaire-collaborative-la-cle-du-progres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/noticias4.webp\",\"contentUrl\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/noticias4.webp\",\"width\":1920,\"height\":1056,\"caption\":\"economia circular colaborativa clave para avanzar\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/\",\"name\":\"Erum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#organization\",\"name\":\"Erum\",\"url\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/erum_og.jpg\",\"contentUrl\":\"https:\\\/\\\/erumgroup.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/erum_og.jpg\",\"width\":200,\"height\":200,\"caption\":\"Erum\"},\"image\":{\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/plasticoserum\\\/\",\"https:\\\/\\\/x.com\\\/Erumgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/erumgroup\\\/\",\"https:\\\/\\\/www.instagram.com\\\/erumgroup\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/#\\\/schema\\\/person\\\/80652ce28a8d027d641a57d62f8d823c\",\"name\":\"tttsergio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g\",\"caption\":\"tttsergio\"},\"url\":\"https:\\\/\\\/erumgroup.com\\\/fr\\\/author\\\/tttsergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s - Erum","description":"Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s","og_description":"Chez Erum, ce mod\u00e8le et ce changement de mentalit\u00e9 se pratiquent depuis longtemps, gr\u00e2ce \u00e0 notre volont\u00e9 d\u2019\u00eatre visionnaires et d\u2019interpr\u00e9ter l\u2019avenir, de consid\u00e9rer les g\u00e9n\u00e9rations futures","og_url":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/","og_site_name":"Erum","article_publisher":"https:\/\/www.facebook.com\/plasticoserum\/","article_published_time":"2022-12-12T00:21:46+00:00","article_modified_time":"2026-02-18T15:13:46+00:00","og_image":[{"url":"https:\/\/erumgroup.com\/wp-content\/uploads\/2022\/12\/noticias4-1024x563.webp","type":"","width":"","height":""}],"author":"tttsergio","twitter_card":"summary_large_image","twitter_title":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s","twitter_description":"Chez Erum, ce mod\u00e8le et ce changement de mentalit\u00e9 se pratiquent depuis longtemps, gr\u00e2ce \u00e0 notre volont\u00e9 d\u2019\u00eatre visionnaires et d\u2019interpr\u00e9ter l\u2019avenir, de consid\u00e9rer les g\u00e9n\u00e9rations futures","twitter_creator":"@Erumgroup","twitter_site":"@Erumgroup","twitter_misc":{"\u00c9crit par":"tttsergio","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/#article","isPartOf":{"@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/"},"author":{"name":"tttsergio","@id":"https:\/\/erumgroup.com\/fr\/#\/schema\/person\/80652ce28a8d027d641a57d62f8d823c"},"headline":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s","datePublished":"2022-12-12T00:21:46+00:00","dateModified":"2026-02-18T15:13:46+00:00","mainEntityOfPage":{"@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/"},"wordCount":774,"publisher":{"@id":"https:\/\/erumgroup.com\/fr\/#organization"},"image":{"@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/#primaryimage"},"thumbnailUrl":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/noticias4.webp","articleSection":["Circular Thinking"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/","url":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/","name":"\u00c9conomie Ciculaire Collaborative: La clu\u00e9 du progr\u00e8s - Erum","isPartOf":{"@id":"https:\/\/erumgroup.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/#primaryimage"},"image":{"@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/#primaryimage"},"thumbnailUrl":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/noticias4.webp","datePublished":"2022-12-12T00:21:46+00:00","dateModified":"2026-02-18T15:13:46+00:00","description":"Chez Erum, nous avons une longue exp\u00e9rience en mati\u00e8re d\u2019injection plastique selon des crit\u00e8res de durabilit\u00e9 et d\u2019efficacit\u00e9","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/erumgroup.com\/fr\/economie-circulaire-collaborative-la-cle-du-progres\/#primaryimage","url":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/noticias4.webp","contentUrl":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/noticias4.webp","width":1920,"height":1056,"caption":"economia circular colaborativa clave para avanzar"},{"@type":"WebSite","@id":"https:\/\/erumgroup.com\/fr\/#website","url":"https:\/\/erumgroup.com\/fr\/","name":"Erum","description":"","publisher":{"@id":"https:\/\/erumgroup.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erumgroup.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/erumgroup.com\/fr\/#organization","name":"Erum","url":"https:\/\/erumgroup.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/erumgroup.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/erum_og.jpg","contentUrl":"https:\/\/erumgroup.com\/wp-content\/uploads\/2026\/02\/erum_og.jpg","width":200,"height":200,"caption":"Erum"},"image":{"@id":"https:\/\/erumgroup.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/plasticoserum\/","https:\/\/x.com\/Erumgroup","https:\/\/www.linkedin.com\/company\/erumgroup\/","https:\/\/www.instagram.com\/erumgroup\/"]},{"@type":"Person","@id":"https:\/\/erumgroup.com\/fr\/#\/schema\/person\/80652ce28a8d027d641a57d62f8d823c","name":"tttsergio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d784eb269c2a98b5a6554957106dd2b013a3564370fb72e547d2d18c70804c50?s=96&d=mm&r=g","caption":"tttsergio"},"url":"https:\/\/erumgroup.com\/fr\/author\/tttsergio\/"}]}},"_links":{"self":[{"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/posts\/1750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/comments?post=1750"}],"version-history":[{"count":3,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/posts\/1750\/revisions"}],"predecessor-version":[{"id":2934,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/posts\/1750\/revisions\/2934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/media\/1736"}],"wp:attachment":[{"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/media?parent=1750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/categories?post=1750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erumgroup.com\/fr\/wp-json\/wp\/v2\/tags?post=1750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}